{"id":36185,"date":"2022-09-13T17:27:46","date_gmt":"2022-09-13T15:27:46","guid":{"rendered":"https:\/\/oplitegames.com\/?page_id=36185"},"modified":"2025-02-14T12:50:37","modified_gmt":"2025-02-14T11:50:37","slug":"cgu","status":"publish","type":"page","link":"https:\/\/oplitegames.com\/it\/cgu\/","title":{"rendered":"CGU"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"36185\" class=\"elementor elementor-36185 elementor-14319\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef6eb43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef6eb43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90ebbdc\" data-id=\"90ebbdc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee67f19 elementor-widget elementor-widget-spacer\" data-id=\"ee67f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bef76c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bef76c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a858499\" data-id=\"a858499\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86d1ca1 elementor-widget elementor-widget-text-editor\" data-id=\"86d1ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"textLayer\" style=\"text-align: center;\"><strong>MENTIONS L\u00c9GALES ET CONDITIONS D&#8217;UTILISATION DU SITE INTERNET : www.oplitegames.com<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\">La poursuite de la navigation sur le site www.oplitegames.com vaut acceptation sans r\u00e9serve des<br>dispositions et conditions d&#8217;utilisation qui suivent.<br>La version actuellement en ligne de ces conditions d&#8217;utilisation est la seule opposable pendant toute la<br>dur\u00e9e d&#8217;utilisation du site et jusqu&#8217;\u00e0 ce qu&#8217;une nouvelle version la remplace.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 1 &#8211; Informations l\u00e9gales<\/strong><\/div>\n<div class=\"textLayer\">1.1 &#8211; Site (ci-apr\u00e8s \u00ab le site \u00bb) : www.oplitegames.com<br>1.2 &#8211; \u00c9diteur (ci-apr\u00e8s \u00ab l&#8217;\u00e9diteur \u00bb) :<br>EXERTIS FRANCE, soci\u00e9t\u00e9 par actions simplifi\u00e9e au capital de 2 818 960 euros dont le si\u00e8ge social est situ\u00e9<br>5 rue Pleyel 93200 SAINT DENIS<br>340 062 173 RCS BOBIGNY, N\u00b0 TVA intracommunautaire FR 89 340 062 173.<br>Num\u00e9ro de t\u00e9l\u00e9phone : pr\u00e9ciser le num\u00e9ro de t\u00e9l\u00e9phone d&#8217;accueil de la soci\u00e9t\u00e9<br>Adresse de courrier \u00e9lectronique : contact@exertis.fr<br>Directeur de la publication : Jeremy Benmoussa<br>1.3 &#8211; Conception et r\u00e9alisation : Exertis France<br>1.4 &#8211; H\u00e9bergeur (ci-apr\u00e8s \u00ab l&#8217;h\u00e9bergeur \u00bb) : Microsoft Azure.<br>Num\u00e9ro de t\u00e9l\u00e9phone : 01 56 47 04 70<br>Adresse de courrier \u00e9lectronique : sav@exertis.fr<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 2 &#8211; Acc\u00e8s au site<\/strong><\/div>\n<div class=\"textLayer\">L&#8217;acc\u00e8s au site est r\u00e9serv\u00e9 aux personnes majeures. L&#8217;\u00e9diteur se r\u00e9serve le droit de demander toute<br>justification de votre \u00e2ge notamment si vous utilisez des services de commande en ligne.<br>L&#8217;acc\u00e8s au site et son utilisation sont r\u00e9serv\u00e9s \u00e0 un usage strictement personnel. Vous vous engagez \u00e0 ne<br>pas utiliser ce site et les informations ou donn\u00e9es qui y figurent \u00e0 des fins commerciales, politiques,<br>publicitaires et pour toute forme de sollicitation commerciale et notamment l&#8217;envoi de courriers<br>\u00e9lectroniques non sollicit\u00e9s.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 3 &#8211; Contenu du site<\/strong><\/div>\n<div class=\"textLayer\">Toutes les marques, photographies, textes, commentaires, illustrations, images anim\u00e9es ou non,<br>s\u00e9quences vid\u00e9o, sons, ainsi que toutes les applications informatiques qui pourraient \u00eatre utilis\u00e9es pour<br>faire fonctionner ce site et plus g\u00e9n\u00e9ralement tous les \u00e9l\u00e9ments reproduits ou utilis\u00e9s sur le site sont<br>prot\u00e9g\u00e9s par les lois en vigueur au titre de la propri\u00e9t\u00e9 intellectuelle.<br>Ils sont la propri\u00e9t\u00e9 pleine et enti\u00e8re de l&#8217;\u00e9diteur ou de ses partenaires. Toute reproduction,<br>repr\u00e9sentation, utilisation ou adaptation, sous quelque forme que ce soit, de tout ou partie de ces<br>\u00e9l\u00e9ments, y compris les applications informatiques, sans l&#8217;accord pr\u00e9alable et \u00e9crit de l&#8217;\u00e9diteur, sont<br>strictement interdites. Le fait pour l&#8217;\u00e9diteur de ne pas engager de proc\u00e9dure d\u00e8s la prise de connaissance<br>de ces utilisations non autoris\u00e9es ne vaut pas acceptation desdites utilisations et renonciation aux<br>poursuites.<br>En ce qui concerne les services de commande en ligne, l&#8217;ensemble des informations pr\u00e9sentes sur ce site<br>sont valables pour la France m\u00e9tropolitaine (Corse incluse) exclusivement. Pour toute commande destin\u00e9e<br>\u00e0 d&#8217;autres destinations, vous devez demander via l&#8217;adresse e-mail de l&#8217;\u00e9diteur ci-dessous, les informations<br>n\u00e9cessaires.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 4 &#8211; Gestion du site<\/strong><\/div>\n<div class=\"textLayer\">Pour la bonne gestion du site, l&#8217;\u00e9diteur pourra \u00e0 tout moment :<br>-suspendre, interrompre ou de limiter l&#8217;acc\u00e8s \u00e0 tout ou partie du site, r\u00e9server l&#8217;acc\u00e8s au site, ou \u00e0<br>certaines parties du site, \u00e0 une cat\u00e9gorie d\u00e9termin\u00e9e d&#8217;internaute ;<br>-supprimer toute information pouvant en perturber le fonctionnement ou entrant en contravention<br>avec les lois nationales ou internationales, ou avec les r\u00e8gles de la N\u00e9tiquette ;<br>-suspendre le site afin de proc\u00e9der \u00e0 des mises \u00e0 jour.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 5 &#8211; Responsabilit\u00e9s<\/strong><\/div>\n<div class=\"textLayer\">La responsabilit\u00e9 de l&#8217;\u00e9diteur ne peut \u00eatre engag\u00e9e en cas de d\u00e9faillance, panne, difficult\u00e9 ou interruption<br>de fonctionnement, emp\u00eachant l&#8217;acc\u00e8s au site ou \u00e0 une de ses fonctionnalit\u00e9s.<br>Le mat\u00e9riel de connexion au site que vous utilisez est sous votre enti\u00e8re responsabilit\u00e9. Vous devez<br>prendre toutes les mesures appropri\u00e9es pour prot\u00e9ger votre mat\u00e9riel et vos propres donn\u00e9es notamment<br>d&#8217;attaques virales par Internet. Vous \u00eates par ailleurs le seul responsable des sites et donn\u00e9es que vous<br>consultez.<br>L&#8217;\u00e9diteur ne pourra \u00eatre tenu responsable en cas de poursuites judiciaires \u00e0 votre encontre :<br>-du fait de l&#8217;usage du site ou de tout service accessible via Internet ;<br>-du fait du non-respect par vous des pr\u00e9sentes conditions g\u00e9n\u00e9rales.<br>L&#8217;\u00e9diteur n&#8217;est pas responsable des dommages caus\u00e9s \u00e0 vous-m\u00eame, \u00e0 des tiers et\/ou \u00e0 votre \u00e9quipement<br>du fait de votre connexion ou de votre utilisation du site et vous renoncez \u00e0 toute action contre lui de ce<br>fait.<br>Si l&#8217;\u00e9diteur venait \u00e0 faire l&#8217;objet d&#8217;une proc\u00e9dure amiable ou judiciaire \u00e0 raison de votre utilisation du site,<br>il pourra retourner contre vous pour obtenir indemnisation de tous les pr\u00e9judices, sommes,<br>condamnations et frais qui pourraient d\u00e9couler de cette proc\u00e9dure.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 6 &#8211; Liens hypertextes<\/strong><\/div>\n<div class=\"textLayer\">La mise en place par vous de tous liens hypertextes vers tout ou partie du site est strictement interdite,<br>sauf autorisation pr\u00e9alable et \u00e9crite de l&#8217;\u00e9diteur, sollicit\u00e9e par courriel \u00e0 l&#8217;adresse suivante : si\u00e8ge social<br>de l&#8217;\u00e9diteur.<br>L&#8217;\u00e9diteur est libre de refuser cette autorisation sans avoir \u00e0 justifier de quelque mani\u00e8re que ce soit sa<br>d\u00e9cision. Dans le cas o\u00f9 l&#8217;\u00e9diteur accorderait son autorisation, celle-ci n&#8217;est dans tous les cas que<br>temporaire et pourra \u00eatre retir\u00e9e \u00e0 tout moment, sans obligation de justification \u00e0 la charge de l&#8217;\u00e9diteur.<br>Dans tous les cas, tout lien devra \u00eatre retir\u00e9 sur simple demande de l&#8217;\u00e9diteur.<br>Toute information accessible via un lien vers d&#8217;autres sites n&#8217;est pas sous le contr\u00f4le de l&#8217;\u00e9diteur qui d\u00e9cline<br>toute responsabilit\u00e9 quant \u00e0 leur contenu.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 7 &#8211; Protection des donn\u00e9es \u00e0 caract\u00e8re personnel<\/strong><\/div>\n<div class=\"textLayer\">7.1 &#8211; Collecte des donn\u00e9es personnelles<br>Les donn\u00e9es \u00e0 caract\u00e8re personnel qui sont collect\u00e9es sur ce site (ou \u00ab Plateforme \u00bb) sont les suivantes :<\/div>\n<div class=\"textLayer\">7.1.1 &#8211; Ouverture de compte<br>Lors de la cr\u00e9ation du compte de l&#8217;utilisateur, ses nom, pr\u00e9nom, adresse \u00e9lectronique et date de naissance.<\/div>\n<div class=\"textLayer\">7.1.2 &#8211; Connexion<br>Lors de la connexion de l&#8217;utilisateur \u00e0 la Plateforme, celle-ci enregistre, notamment, ses nom, pr\u00e9nom,<br>donn\u00e9es de connexion, d&#8217;utilisation, de localisation et ses donn\u00e9es relatives au paiement.<\/div>\n<div class=\"textLayer\">7.1.3 &#8211; Profil<br>L&#8217;utilisation des prestations pr\u00e9vues sur la Plateforme permet de renseigner un profil, pouvant<br>comprendre une adresse et un num\u00e9ro de t\u00e9l\u00e9phone.<\/div>\n<div class=\"textLayer\">7.1.4 &#8211; Paiement<br>Dans le cadre du paiement des produits et prestations propos\u00e9s sur la Plateforme, celle-ci enregistre des<br>donn\u00e9es financi\u00e8res relatives au compte bancaire ou \u00e0 la carte de cr\u00e9dit de l&#8217;utilisateur.<\/div>\n<div class=\"textLayer\">7.1.5 &#8211; Communication<br>Lorsque la Plateforme est utilis\u00e9e pour communiquer avec d&#8217;autres membres, les donn\u00e9es concernant les<br>communications de l&#8217;utilisateur font l&#8217;objet d&#8217;une conservation temporaire.<\/div>\n<div class=\"textLayer\">7.1.6 &#8211; Cookies<br>Les cookies sont utilis\u00e9s, dans le cadre de l&#8217;utilisation du site. L&#8217;utilisateur a la possibilit\u00e9 de d\u00e9sactiver les<br>cookies \u00e0 partir des param\u00e8tres de son navigateur.<\/div>\n<div class=\"textLayer\">7.2 &#8211; Utilisation des donn\u00e9es personnelles<br>Les donn\u00e9es personnelles collect\u00e9es aupr\u00e8s des utilisateurs ont pour objectif la mise \u00e0 disposition des<br>services de la Plateforme, leur am\u00e9lioration et le maintien d&#8217;un environnement s\u00e9curis\u00e9. Plus pr\u00e9cis\u00e9ment,<br>les utilisations sont les suivantes :<br>-acc\u00e8s et utilisation de la Plateforme par l&#8217;utilisateur ;<br>-gestion du fonctionnement et optimisation de la Plateforme ;<br>-organisation des conditions d&#8217;utilisation des Services de paiement ;<br>-v\u00e9rification, identification et authentification des donn\u00e9es transmises par l&#8217;utilisateur ;<br>-proposition \u00e0 l&#8217;utilisateur de la possibilit\u00e9 de communiquer avec d&#8217;autres utilisateurs de la<br>Plateforme ;<br>-mise en oeuvre d&#8217;une assistance utilisateurs ;<br>-personnalisation des services en affichant des publicit\u00e9s en fonction de l&#8217;historique de navigation de<br>l&#8217;utilisateur, selon ses pr\u00e9f\u00e9rences ;<br>-pr\u00e9vention et d\u00e9tection des fraudes, malwares (malicious softwares ou logiciels malveillants) et<br>gestion des incidents de s\u00e9curit\u00e9 ;<br>-gestion des \u00e9ventuels litiges avec les utilisateurs ;-envoi d&#8217;informations commerciales et publicitaires, en fonction des pr\u00e9f\u00e9rences de l&#8217;utilisateur.<\/div>\n<div class=\"textLayer\">7.3 &#8211; Partage des donn\u00e9es personnelles avec des tiers<br>Les donn\u00e9es personnelles peuvent \u00eatre partag\u00e9es avec des soci\u00e9t\u00e9s tierces, dans les cas suivants :<br>-quand l&#8217;utilisateur utilise les services de paiement, pour la mise en oeuvre de ces services, la<br>Plateforme est en relation avec des soci\u00e9t\u00e9s bancaires et financi\u00e8res tierces avec lesquelles elle a<br>pass\u00e9 des contrats ;<br>-lorsque l&#8217;utilisateur publie, dans les zones de commentaires libres de la Plateforme, des informations<br>accessibles au public ;<br>-quand l&#8217;utilisateur autorise le site web d&#8217;un tiers \u00e0 acc\u00e9der \u00e0 ses donn\u00e9es ;<br>-quand la Plateforme recourt aux services de prestataires pour fournir l&#8217;assistance utilisateurs, la<br>publicit\u00e9 et les services de paiement. Ces prestataires disposent d&#8217;un acc\u00e8s limit\u00e9 aux donn\u00e9es de<br>l&#8217;utilisateur, dans le cadre de l&#8217;ex\u00e9cution de ces prestations, et ont une obligation contractuelle de les<br>utiliser en conformit\u00e9 avec les dispositions de la r\u00e9glementation applicable en mati\u00e8re protection des<br>donn\u00e9es \u00e0 caract\u00e8re personnel ;<br>-si la loi l&#8217;exige, la Plateforme peut effectuer la transmission de donn\u00e9es pour donner suite aux<br>r\u00e9clamations pr\u00e9sent\u00e9es contre la Plateforme et se conformer aux proc\u00e9dures administratives et<br>judiciaires ;<br>-si la Plateforme est impliqu\u00e9e dans une op\u00e9ration de fusion, acquisition, cession d&#8217;actifs ou proc\u00e9dure<br>de redressement judiciaire, elle pourra \u00eatre amen\u00e9e \u00e0 c\u00e9der ou partager tout ou partie de ses actifs,<br>y compris les donn\u00e9es \u00e0 caract\u00e8re personnel. Dans ce cas, les utilisateurs seraient inform\u00e9s, avant que<br>les donn\u00e9es \u00e0 caract\u00e8re personnel ne soient transf\u00e9r\u00e9es \u00e0 une tierce partie.<\/div>\n<div class=\"textLayer\">7.5 &#8211; S\u00e9curit\u00e9 et confidentialit\u00e9<br>La Plateforme met en oeuvre des mesures organisationnelles, techniques, logicielles et physiques en<br>mati\u00e8re de s\u00e9curit\u00e9 du num\u00e9rique pour prot\u00e9ger les donn\u00e9es personnelles contre les alt\u00e9rations,<br>destructions et acc\u00e8s non autoris\u00e9s. Toutefois, il est \u00e0 signaler qu&#8217;internet n&#8217;est pas un environnement<br>compl\u00e8tement s\u00e9curis\u00e9 et la Plateforme ne peut pas garantir la s\u00e9curit\u00e9 de la transmission ou du stockage<br>des informations sur internet.<\/div>\n<div class=\"textLayer\">7.6 &#8211; Mise en oeuvre des droits des utilisateurs<br>En application de la r\u00e9glementation applicable aux donn\u00e9es \u00e0 caract\u00e8re personnel, les utilisateurs<br>disposent des droits suivants :<br>-ils peuvent mettre \u00e0 jour ou supprimerles donn\u00e9es qui les concernent en se connectant \u00e0 leur compte<br>et en configurant les param\u00e8tres de ce compte ;<br>-ils peuvent supprimer leur compte, en \u00e9crivant \u00e0 l&#8217;adresse \u00e9lectronique suivante : contact@exertis.fr.<br>Il est \u00e0 noter que les informations partag\u00e9es avec d&#8217;autres utilisateurs, comme les publications sur les<br>forums, peuvent rester visibles du public sur la Plateforme, m\u00eame apr\u00e8s la suppression de leur<br>compte ;<br>-ils peuvent exercer leur droit d&#8217;acc\u00e8s, pour conna\u00eetre les donn\u00e9es personnelles les concernant, en<br>\u00e9crivant \u00e0 l&#8217;adresse \u00e9lectronique suivante : contact@exertis.fr. Dans ce cas, avant la mise en oeuvre<br>de ce droit, la Plateforme peut demander une preuve de l&#8217;identit\u00e9 de l&#8217;utilisateur afin d&#8217;en v\u00e9rifier<br>l&#8217;exactitude ;<br>-si les donn\u00e9es \u00e0 caract\u00e8re personnel d\u00e9tenues par la Plateforme sont inexactes, ils peuvent demander<br>la mise \u00e0 jour des informations, en \u00e9crivant \u00e0 l&#8217;adresse \u00e9lectronique suivante : contact@exertis.fr;<br>-les utilisateurs peuvent demander la suppression de leurs donn\u00e9es \u00e0 caract\u00e8re personnel,<br>conform\u00e9ment aux lois applicables en mati\u00e8re de protection des donn\u00e9es, en \u00e9crivant \u00e0 l&#8217;adresse<br>\u00e9lectronique suivante : contact@exertis.fr.<\/div>\n<div class=\"textLayer\">7.7 &#8211; \u00c9volution de la pr\u00e9sente clause<br>La Plateforme se r\u00e9serve le droit d&#8217;apporter toute modification \u00e0 la pr\u00e9sente clause relative \u00e0 la protection<br>des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 tout moment. Si une modification est apport\u00e9e \u00e0 la pr\u00e9sente clause<br>de protection des donn\u00e9es \u00e0 caract\u00e8re personnel, la Plateforme s&#8217;engage \u00e0 publier la nouvelle version sur<br>son site. La Plateforme informera \u00e9galement les utilisateurs de la modification par messagerie<br>\u00e9lectronique, dans un d\u00e9lai minimum de 15 jours avant la date d&#8217;effet. Si l&#8217;utilisateur n&#8217;est pas d&#8217;accord<br>avec les termes de la nouvelle r\u00e9daction de la clause de protection des donn\u00e9es \u00e0 caract\u00e8re personnel, il<br>a la possibilit\u00e9 de supprimer son compte.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 8 &#8211; Cookies \u2013 Informations collect\u00e9es<\/strong><\/div>\n<div class=\"textLayer\">Le site peut collecter automatiquement des informations standards. Toutes les informations collect\u00e9es<br>indirectement ne seront utilis\u00e9es que pour suivre le volume, le type et la configuration du trafic utilisant<br>ce site, pour en d\u00e9velopper la conception et l&#8217;agencement et \u00e0 d&#8217;autres fins administratives et de<br>planification et plus g\u00e9n\u00e9ralement pour am\u00e9liorer le service que nous vous offrons.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 9 &#8211; Photographies et repr\u00e9sentation des produits<\/strong><\/div>\n<div class=\"textLayer\">Les photographies de produits, accompagnant leur description, ne sont pas contractuelles et n&#8217;engagent<br>pas l&#8217;\u00e9diteur.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 10 &#8211; Loi applicable<\/strong><br>Les pr\u00e9sentes conditions d&#8217;utilisation du site sont r\u00e9gies par la loi fran\u00e7aise et soumises \u00e0 la comp\u00e9tence<br>des tribunaux de Paris.<\/div>\n<div>&nbsp;<\/div>\n<div class=\"textLayer\"><strong>Article 11 &#8211; Contactez-nous<\/strong><br>Pour toute question, information sur les produits pr\u00e9sent\u00e9s sur le site, ou concernant le site lui-m\u00eame,<br>vous pouvez laisser un message \u00e0 l&#8217;adresse suivante : contact@exertis.f<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MENTIONS L\u00c9GALES ET CONDITIONS D&#8217;UTILISATION DU SITE INTERNET : www.oplitegames.com &nbsp; La poursuite de la navigation sur le site www.oplitegames.com vaut acceptation sans r\u00e9serve desdispositions et conditions d&#8217;utilisation qui suivent.La&#8230;<\/p>\n","protected":false},"author":114,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-36185","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CGU - OPLITE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oplitegames.com\/it\/cgu\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CGU - OPLITE\" \/>\n<meta property=\"og:description\" content=\"MENTIONS L\u00c9GALES ET CONDITIONS D&#8217;UTILISATION DU SITE INTERNET : www.oplitegames.com &nbsp; La poursuite de la navigation sur le site www.oplitegames.com vaut acceptation sans r\u00e9serve desdispositions et conditions d&#8217;utilisation qui suivent.La...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oplitegames.com\/it\/cgu\/\" \/>\n<meta property=\"og:site_name\" content=\"OPLITE\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-14T11:50:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oplitegames.com\/it\/cgu\/\",\"url\":\"https:\/\/oplitegames.com\/it\/cgu\/\",\"name\":\"CGU - OPLITE\",\"isPartOf\":{\"@id\":\"https:\/\/oplitegames.com\/#website\"},\"datePublished\":\"2022-09-13T15:27:46+00:00\",\"dateModified\":\"2025-02-14T11:50:37+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oplitegames.com\/it\/cgu\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oplitegames.com\/#website\",\"url\":\"https:\/\/oplitegames.com\/\",\"name\":\"OPLITE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/oplitegames.com\/#organization\"},\"alternateName\":\"Oplite\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oplitegames.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oplitegames.com\/#organization\",\"name\":\"OPLITE\",\"alternateName\":\"Oplite\",\"url\":\"https:\/\/oplitegames.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/oplitegames.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oplitegames.com\/wp-content\/uploads\/cropped-Favicon_oplite.jpg\",\"contentUrl\":\"https:\/\/oplitegames.com\/wp-content\/uploads\/cropped-Favicon_oplite.jpg\",\"width\":512,\"height\":512,\"caption\":\"OPLITE\"},\"image\":{\"@id\":\"https:\/\/oplitegames.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CGU - OPLITE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oplitegames.com\/it\/cgu\/","og_locale":"it_IT","og_type":"article","og_title":"CGU - OPLITE","og_description":"MENTIONS L\u00c9GALES ET CONDITIONS D&#8217;UTILISATION DU SITE INTERNET : www.oplitegames.com &nbsp; La poursuite de la navigation sur le site www.oplitegames.com vaut acceptation sans r\u00e9serve desdispositions et conditions d&#8217;utilisation qui suivent.La...","og_url":"https:\/\/oplitegames.com\/it\/cgu\/","og_site_name":"OPLITE","article_modified_time":"2025-02-14T11:50:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oplitegames.com\/it\/cgu\/","url":"https:\/\/oplitegames.com\/it\/cgu\/","name":"CGU - OPLITE","isPartOf":{"@id":"https:\/\/oplitegames.com\/#website"},"datePublished":"2022-09-13T15:27:46+00:00","dateModified":"2025-02-14T11:50:37+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oplitegames.com\/it\/cgu\/"]}]},{"@type":"WebSite","@id":"https:\/\/oplitegames.com\/#website","url":"https:\/\/oplitegames.com\/","name":"OPLITE","description":"","publisher":{"@id":"https:\/\/oplitegames.com\/#organization"},"alternateName":"Oplite","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oplitegames.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/oplitegames.com\/#organization","name":"OPLITE","alternateName":"Oplite","url":"https:\/\/oplitegames.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/oplitegames.com\/#\/schema\/logo\/image\/","url":"https:\/\/oplitegames.com\/wp-content\/uploads\/cropped-Favicon_oplite.jpg","contentUrl":"https:\/\/oplitegames.com\/wp-content\/uploads\/cropped-Favicon_oplite.jpg","width":512,"height":512,"caption":"OPLITE"},"image":{"@id":"https:\/\/oplitegames.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oplitegames.com\/it\/wp-json\/wp\/v2\/pages\/36185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oplitegames.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oplitegames.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oplitegames.com\/it\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/oplitegames.com\/it\/wp-json\/wp\/v2\/comments?post=36185"}],"version-history":[{"count":4,"href":"https:\/\/oplitegames.com\/it\/wp-json\/wp\/v2\/pages\/36185\/revisions"}],"predecessor-version":[{"id":47542,"href":"https:\/\/oplitegames.com\/it\/wp-json\/wp\/v2\/pages\/36185\/revisions\/47542"}],"wp:attachment":[{"href":"https:\/\/oplitegames.com\/it\/wp-json\/wp\/v2\/media?parent=36185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}